{"id":2505,"date":"2023-01-27T15:06:31","date_gmt":"2023-01-27T18:06:31","guid":{"rendered":"https:\/\/www.salinas.com.br\/post\/salinas-maceio-magia-tropical-natal"},"modified":"2025-09-18T18:18:14","modified_gmt":"2025-09-18T21:18:14","slug":"o-salinas-maceio-marcou-o-natal-com-muita-magia-tropical","status":"publish","type":"post","link":"https:\/\/www.salinas.com.br\/blog\/o-salinas-maceio-marcou-o-natal-com-muita-magia-tropical\/","title":{"rendered":"O Salinas Macei\u00f3 marcou o natal com muita magia tropical"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">A Magia Tropical tomou conta do <\/span><a href=\"https:\/\/www.salinas.com.br\/pt\/maceio\/\"><strong>Salinas Macei\u00f3<\/strong><\/a><span style=\"font-weight: 400;\"> no per\u00edodo natalino, proporcionando uma experi\u00eancia inesquec\u00edvel para os h\u00f3spedes. Al\u00e9m da ceia de natal e a presen\u00e7a do Papai Noel, teve entrega de presentes e shows para todas as idades \ud83d\ude03<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/gwm.salinas.com.br\/uploads\/blog\/images\/63d4116c2ada2.salinas-maceio-all-inclusive-natal.jpg\" alt=\"\" width=\"1540\" height=\"1027\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">A ceia aconteceu no Sports Bar e teve as mesas alocadas no Garden, o ambiente foi totalmente remodelado para transformar o ambiente ainda mais aconchegante, como um bom natal em fam\u00edlia\u00a0<span class=\"cqiun4t2 khvhiq1o r5qsrrlp i5tg98hk iqx13udk przvwfww qiohso4h gfz4du6o r7fjleex nz2484kf svot0ezm dcnh1tix sxl192xd t3g6t33p\"><span class=\"\">\ud83d\udc99<\/span><\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\"><span class=\"cqiun4t2 khvhiq1o r5qsrrlp i5tg98hk iqx13udk przvwfww qiohso4h gfz4du6o r7fjleex nz2484kf svot0ezm dcnh1tix sxl192xd t3g6t33p\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/gwm.salinas.com.br\/uploads\/blog\/images\/63d411b3dc918.salinas-maceio-all-inclusive-ceia-natal.jpg\" alt=\"\" width=\"1540\" height=\"1027\" \/><\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Ah, e n\u00e3o d\u00e1 pra falar de natal sem a presen\u00e7a do Papai Noel, n\u00e9? No Salinas Macei\u00f3 All Inclusive Resort, o bom velhinho chegou de quadriciclo e distribuindo presentes \ud83e\uddd1\u200d\ud83c\udf84\ud83c\udf81<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/gwm.salinas.com.br\/uploads\/blog\/images\/63d411d6b7555.salinas-maceio-papai-noel-natal.jpg\" alt=\"\" width=\"1540\" height=\"1027\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">O tema da festa, que foi &#8220;Magia Tropical&#8221;, esteve presente em todos os ambientes do resort, deixando o clima perfeito para o natal em fam\u00edlia. A cenografia foi assinada por Kathellen Carvalho.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/gwm.salinas.com.br\/uploads\/blog\/images\/63d411feec197.salinas-maceio-natal-ceia.jpg\" alt=\"\" width=\"1540\" height=\"1027\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Incr\u00edvel, n\u00e9? N\u00e3o perde tempo e j\u00e1 <a href=\"https:\/\/www.salinas.com.br\/pt\/maceio\/promocoes\">clica aqui<\/a> para garantir a sua reserva para o natal de 2023 do Salinas Macei\u00f3 \ud83d\udc99<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Magia Tropical tomou conta do Salinas Macei\u00f3 no per\u00edodo natalino, proporcionando uma experi\u00eancia inesquec\u00edvel para os h\u00f3spedes. Al\u00e9m da ceia de natal e a presen\u00e7a do Papai Noel, teve entrega de presentes e shows para todas as idades \ud83d\ude03 A ceia aconteceu no Sports Bar e teve as mesas alocadas no Garden, o ambiente [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":2870,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[111],"tags":[],"class_list":["post-2505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diversao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>O Salinas Macei\u00f3 marcou o natal com muita magia tropical - Amarante<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salinas.com.br\/blog\/o-salinas-maceio-marcou-o-natal-com-muita-magia-tropical\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O Salinas Macei\u00f3 marcou o natal com muita magia tropical - Amarante\" \/>\n<meta property=\"og:description\" content=\"A Magia Tropical tomou conta do Salinas Macei\u00f3 no per\u00edodo natalino, proporcionando uma experi\u00eancia inesquec\u00edvel para os h\u00f3spedes. Al\u00e9m da ceia de natal e a presen\u00e7a do Papai Noel, teve entrega de presentes e shows para todas as idades \ud83d\ude03 A ceia aconteceu no Sports Bar e teve as mesas alocadas no Garden, o ambiente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salinas.com.br\/blog\/o-salinas-maceio-marcou-o-natal-com-muita-magia-tropical\/\" \/>\n<meta property=\"og:site_name\" content=\"Amarante\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-27T18:06:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-18T21:18:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salinas.com.br\/blog\/wp-content\/uploads\/2023\/01\/o-salinas-mcz-marcou-o-natal-com-muita-magia.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"410\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Amarante\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Amarante\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.salinas.com.br\/blog\/o-salinas-maceio-marcou-o-natal-com-muita-magia-tropical\/\",\"url\":\"https:\/\/www.salinas.com.br\/blog\/o-salinas-maceio-marcou-o-natal-com-muita-magia-tropical\/\",\"name\":\"O Salinas Macei\u00f3 marcou o natal com muita magia tropical - Amarante\",\"isPartOf\":{\"@id\":\"https:\/\/www.salinas.com.br\/blog\/#website\"},\"datePublished\":\"2023-01-27T18:06:31+00:00\",\"dateModified\":\"2025-09-18T21:18:14+00:00\",\"author\":{\"@id\":\"https:\/\/www.salinas.com.br\/blog\/#\/schema\/person\/b706075dc509e91c28efb76c2d4bdd97\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.salinas.com.br\/blog\/o-salinas-maceio-marcou-o-natal-com-muita-magia-tropical\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.salinas.com.br\/blog\/o-salinas-maceio-marcou-o-natal-com-muita-magia-tropical\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.salinas.com.br\/blog\/o-salinas-maceio-marcou-o-natal-com-muita-magia-tropical\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.salinas.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O Salinas Macei\u00f3 marcou o natal com muita magia tropical\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.salinas.com.br\/blog\/#website\",\"url\":\"https:\/\/www.salinas.com.br\/blog\/\",\"name\":\"Amarante\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.salinas.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.salinas.com.br\/blog\/#\/schema\/person\/b706075dc509e91c28efb76c2d4bdd97\",\"name\":\"Amarante\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.salinas.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b121658c17d0c24a19e905c4d002e7791545e8605f560c9b6896a49ff44b385a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b121658c17d0c24a19e905c4d002e7791545e8605f560c9b6896a49ff44b385a?s=96&d=mm&r=g\",\"caption\":\"Amarante\"},\"url\":\"https:\/\/www.salinas.com.br\/blog\/author\/amarante\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O Salinas Macei\u00f3 marcou o natal com muita magia tropical - Amarante","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salinas.com.br\/blog\/o-salinas-maceio-marcou-o-natal-com-muita-magia-tropical\/","og_locale":"pt_BR","og_type":"article","og_title":"O Salinas Macei\u00f3 marcou o natal com muita magia tropical - Amarante","og_description":"A Magia Tropical tomou conta do Salinas Macei\u00f3 no per\u00edodo natalino, proporcionando uma experi\u00eancia inesquec\u00edvel para os h\u00f3spedes. Al\u00e9m da ceia de natal e a presen\u00e7a do Papai Noel, teve entrega de presentes e shows para todas as idades \ud83d\ude03 A ceia aconteceu no Sports Bar e teve as mesas alocadas no Garden, o ambiente [&hellip;]","og_url":"https:\/\/www.salinas.com.br\/blog\/o-salinas-maceio-marcou-o-natal-com-muita-magia-tropical\/","og_site_name":"Amarante","article_published_time":"2023-01-27T18:06:31+00:00","article_modified_time":"2025-09-18T21:18:14+00:00","og_image":[{"width":410,"height":410,"url":"https:\/\/www.salinas.com.br\/blog\/wp-content\/uploads\/2023\/01\/o-salinas-mcz-marcou-o-natal-com-muita-magia.webp","type":"image\/webp"}],"author":"Amarante","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Amarante","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.salinas.com.br\/blog\/o-salinas-maceio-marcou-o-natal-com-muita-magia-tropical\/","url":"https:\/\/www.salinas.com.br\/blog\/o-salinas-maceio-marcou-o-natal-com-muita-magia-tropical\/","name":"O Salinas Macei\u00f3 marcou o natal com muita magia tropical - Amarante","isPartOf":{"@id":"https:\/\/www.salinas.com.br\/blog\/#website"},"datePublished":"2023-01-27T18:06:31+00:00","dateModified":"2025-09-18T21:18:14+00:00","author":{"@id":"https:\/\/www.salinas.com.br\/blog\/#\/schema\/person\/b706075dc509e91c28efb76c2d4bdd97"},"breadcrumb":{"@id":"https:\/\/www.salinas.com.br\/blog\/o-salinas-maceio-marcou-o-natal-com-muita-magia-tropical\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salinas.com.br\/blog\/o-salinas-maceio-marcou-o-natal-com-muita-magia-tropical\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.salinas.com.br\/blog\/o-salinas-maceio-marcou-o-natal-com-muita-magia-tropical\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.salinas.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"O Salinas Macei\u00f3 marcou o natal com muita magia tropical"}]},{"@type":"WebSite","@id":"https:\/\/www.salinas.com.br\/blog\/#website","url":"https:\/\/www.salinas.com.br\/blog\/","name":"Amarante","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salinas.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.salinas.com.br\/blog\/#\/schema\/person\/b706075dc509e91c28efb76c2d4bdd97","name":"Amarante","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.salinas.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b121658c17d0c24a19e905c4d002e7791545e8605f560c9b6896a49ff44b385a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b121658c17d0c24a19e905c4d002e7791545e8605f560c9b6896a49ff44b385a?s=96&d=mm&r=g","caption":"Amarante"},"url":"https:\/\/www.salinas.com.br\/blog\/author\/amarante\/"}]}},"views":124,"_links":{"self":[{"href":"https:\/\/www.salinas.com.br\/blog\/wp-json\/wp\/v2\/posts\/2505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salinas.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salinas.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salinas.com.br\/blog\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salinas.com.br\/blog\/wp-json\/wp\/v2\/comments?post=2505"}],"version-history":[{"count":2,"href":"https:\/\/www.salinas.com.br\/blog\/wp-json\/wp\/v2\/posts\/2505\/revisions"}],"predecessor-version":[{"id":2871,"href":"https:\/\/www.salinas.com.br\/blog\/wp-json\/wp\/v2\/posts\/2505\/revisions\/2871"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salinas.com.br\/blog\/wp-json\/wp\/v2\/media\/2870"}],"wp:attachment":[{"href":"https:\/\/www.salinas.com.br\/blog\/wp-json\/wp\/v2\/media?parent=2505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salinas.com.br\/blog\/wp-json\/wp\/v2\/categories?post=2505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salinas.com.br\/blog\/wp-json\/wp\/v2\/tags?post=2505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}